{"id":6226,"date":"2014-11-28T15:53:03","date_gmt":"2014-11-28T15:53:03","guid":{"rendered":"http:\/\/ctrl-x.com.mx\/ctrlx\/?p=6226"},"modified":"2014-11-28T15:53:03","modified_gmt":"2014-11-28T15:53:03","slug":"aunque-no-lo-creas-estos-alimentos-son-excelentes-para-tu-salud","status":"publish","type":"post","link":"https:\/\/ctrl-x.com.mx\/ctrlx\/aunque-no-lo-creas-estos-alimentos-son-excelentes-para-tu-salud\/","title":{"rendered":"Aunque no lo creas, estos alimentos son excelentes para tu salud"},"content":{"rendered":"<p><span style=\"color: #333333;\">La industria de los alimentos est\u00e1 llena de <strong>productos nocivos para salud<\/strong>. Algunos compuestos qu\u00edmicos, y algunas formas de preparaci\u00f3n de alimentos pueden resultar peligrosos para el desarrollo normal de algunas funciones corporales. Por ejemplo, es sabido que las comidas ricas en <strong>grasas saturadas<\/strong> aumentan el colesterol en sangre y dificultan el correcto funcionamiento del sistema circulatorio.\u00a0<\/span><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6232\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-000.jpg\" alt=\"Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-000\" width=\"630\" height=\"360\" \/><br \/>\n<span style=\"color: #333333;\">Tambi\u00e9n es cierto que hay muchos <strong>mitos<\/strong> sobre qu\u00e9 comidas son saludables, y cu\u00e1les no. Algunos alimentos se han ganado la fama de ser altamente nocivos para la salud, sin demasiado fundamento. Hoy hablaremos de cinco alimentos que tienen interesantes beneficios para la salud, aunque siempre se haya dicho que son malos. Comencemos, seguro te sorprender\u00e1s con algunos.\u00a0<\/span><\/p>\n<hr \/>\n<h2><strong><span style=\"color: #008080;\">Popcorn<\/span><\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6231\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-001.jpg\" alt=\"Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-001\" width=\"628\" height=\"360\" \/><br \/>\n<span style=\"color: #333333;\">Las <strong>palomitas de ma\u00edz<\/strong> que consigues cuando vas al cine, podr\u00eda ayudarte a reducir el riego de padecer <strong>c\u00e1ncer<\/strong> y enfermedades card\u00edacas gracias a sus <strong>antioxidantes<\/strong>, llamados\u00a0polifenoles. Una porci\u00f3n de <em>pop<\/em>, tiene la cantidad diaria recomendada de antioxidantes, no obstante, a\u00fan debes tener cuidado con la cantidad de manteca que consumes.<\/span><br \/>\n&nbsp;<\/p>\n<h2><span style=\"color: #008080;\"><strong>Golosinas<\/strong><\/span><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6230\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-002.jpg\" alt=\"Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-002\" width=\"630\" height=\"360\" \/><br \/>\n<span style=\"color: #333333;\">Una reciente investigaci\u00f3n demostr\u00f3 que los ni\u00f1os que consum\u00edan cantidades moderadas de dulces regularmente pesaban menos, y ten\u00edan menos riesgo de padecer <strong>enfermedades card\u00edacas<\/strong>. A diferencia de los ni\u00f1os, entre los adultos los dulces influ\u00edan significativamente en el aumento de peso. Sin embargo, tambi\u00e9n demostraron que habitualmente <strong>quienes comen dulces viven m\u00e1s<\/strong><\/span><br \/>\n&nbsp;<\/p>\n<h2><strong><span style=\"color: #008080;\">Pastel de desayuno<\/span><\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6229\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-003_0.jpg\" alt=\"Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-003_0\" width=\"630\" height=\"360\" \/><br \/>\n<span style=\"color: #333333;\">El desayuno es la comida m\u00e1s importante del d\u00eda, eso lo sabemos todos. Una correcta nutrici\u00f3n en la ma\u00f1ana nos dar\u00e1 la energ\u00eda necesaria par el resto del d\u00eda. Una investigaci\u00f3n de la Universidad de Tel Aviv demostr\u00f3 que un desayuno de al menos 600 calor\u00edas, que incluya un postre dulce, ayudaba a <strong>bajar de peso <\/strong>a los adultos. La clave aqu\u00ed es concentrar el consumo de az\u00facares\u00a0y grasas en la ma\u00f1ana, y no distribuirlo a lo largo del d\u00eda.<\/span><br \/>\n&nbsp;<\/p>\n<h2><strong><span style=\"color: #008080;\">Helado de cena<span style=\"font-size: 12px;\">\u00a0<\/span><\/span><\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6228\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-004.jpg\" alt=\"Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-004\" width=\"630\" height=\"360\" \/><br \/>\n<span style=\"color: #333333;\">Un grupo de cient\u00edficos italianos demostr\u00f3 que el aporte de grasas, <strong>prote\u00ednas<\/strong>, az\u00facares y agua de una porci\u00f3n de helado\u00a0es similar a los de una comida promedio. Claro que no puedes sustituir todas tus comidas por helado, pero esta es una excelente excusa para saltearte alguna comida que no te guste demasiado.<\/span><br \/>\n&nbsp;<\/p>\n<h2><strong><span style=\"color: #008080;\">Chocolate<\/span><\/strong><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6227\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-005.jpg\" alt=\"Aunque-no-lo-creas-estos-5-alimentos-son-excelentes-para-tu-salud-005\" width=\"630\" height=\"360\" \/><br \/>\n<span style=\"color: #333333;\">Este manjar siempre encabezar\u00e1 nuestras listas de alimentos saludables. Sin dudas, el mito de que <strong>el chocolate es malo para salud<\/strong>, es el m\u00e1s injusto de todos. El chocolate tiene m\u00faltiples beneficios para nuestro coraz\u00f3n, ya que nivela nuestra presi\u00f3n sangu\u00ednea. Tambi\u00e9n, al ser rico en antioxidantes,<\/span> <strong><a href=\"http:\/\/www.imujer.com\/5655\/beneficios-del-chocolate-para-la-piel\" target=\"_blank\" rel=\"noopener noreferrer\">el chocolate es excelente para la piel<\/a><\/strong>. <span style=\"color: #333333;\">Adem\u00e1s, una reciente investigaci\u00f3n ha demostrado que <strong>el chocolate es bueno para la memoria<\/strong>. \u00a0<\/span><br \/>\n<span style=\"color: #333333;\">Lo cierto es que la clave de una <strong>alimentaci\u00f3n saludable<\/strong> est\u00e1 en el equilibrio de todos los grupos de alimentos. No debemos dejarnos llevar por los <strong>mitos de la alimentaci\u00f3n saludable<\/strong>, ni debemos abusar de ning\u00fan alimento en particular.<\/span><br \/>\n<span style=\"color: #333333;\">Interesante, \u00bfno lo crees? \u00bfSab\u00edas que estos<\/span> <a href=\"http:\/\/listverse.com\/2013\/06\/29\/8-foods-that-are-shockingly-good-for-you\/\" target=\"_blank\" rel=\"noopener noreferrer\">alimentos<\/a> <span style=\"color: #333333;\">pod\u00edan ser buenos para la <strong>salud<\/strong>?\u00a0<\/span><br \/>\n&nbsp;<br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La industria de los alimentos est\u00e1 llena de productos nocivos para salud. Algunos compuestos qu\u00edmicos, y algunas formas de preparaci\u00f3n de alimentos pueden resultar peligrosos para el desarrollo normal de algunas funciones corporales. Por ejemplo, es sabido que las comidas ricas en grasas saturadas aumentan el colesterol en sangre y dificultan el correcto funcionamiento del&hellip; <a class=\"more-link\" href=\"https:\/\/ctrl-x.com.mx\/ctrlx\/aunque-no-lo-creas-estos-alimentos-son-excelentes-para-tu-salud\/\">Seguir leyendo <span class=\"screen-reader-text\">Aunque no lo creas, estos alimentos son excelentes para tu salud<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":6232,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,50],"tags":[279,547,1110,1137,2145,3809,4357,4452,4467,4632],"class_list":["post-6226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-salud","tag-alimentos","tag-aunque-no-lo-creas","tag-colesterol","tag-comidas","tag-funciones-corporales","tag-peligrosos","tag-ricas-en-grasas-saturadas","tag-salud-2","tag-sangre","tag-sistema-circulatorio","entry"],"_links":{"self":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/6226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/comments?post=6226"}],"version-history":[{"count":0,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/6226\/revisions"}],"wp:attachment":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/media?parent=6226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/categories?post=6226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/tags?post=6226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}