{"id":6054,"date":"2014-11-25T21:27:32","date_gmt":"2014-11-25T21:27:32","guid":{"rendered":"http:\/\/ctrl-x.com.mx\/ctrlx\/?p=6054"},"modified":"2014-11-25T21:27:32","modified_gmt":"2014-11-25T21:27:32","slug":"los-coloridos-tatuajes-geometricos-de-sasha-unisex","status":"publish","type":"post","link":"https:\/\/ctrl-x.com.mx\/ctrlx\/los-coloridos-tatuajes-geometricos-de-sasha-unisex\/","title":{"rendered":"Los coloridos tatuajes geom\u00e9tricos de Sasha Unisex"},"content":{"rendered":"<p><b>Sasha Unisex<\/b> es una tatuadora profesional de origen ruso que imprime (o tat\u00faa, en este caso) un estilo muy personal en cada una de sus obras. El trabajo de Sasha se caracteriza por representar a todo tipo de animales creados a partir de formas poligonales, tatuados sobre la piel para despu\u00e9s ser coloreados con una creativa paleta de tonos alegres y vibrantes. A continuaci\u00f3n, los coloridos tatuajes geom\u00e9tricos de Sasha Unisex.<\/p>\n<h3>Tatuajes geom\u00e9tricos de Sasha Unisex<\/h3>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6055\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-14.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-14\" width=\"620\" height=\"1240\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6056\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-13.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-13\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6057\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-12.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-12\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6058\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-11.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-11\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6059\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-10.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-10\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6060\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-9.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-9\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6061\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-8.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-8\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6062\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-7.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-7\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6063\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-6.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-6\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6064\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-5.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-5\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6065\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-4.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-4\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6066\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-3.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-3\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6067\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-2.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-2\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6068\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex-1.jpg\" alt=\"tatuajes-geometricos-sasha-unisex-1\" width=\"620\" height=\"620\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6069\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2014\/11\/tatuajes-geometricos-sasha-unisex.jpg\" alt=\"tatuajes-geometricos-sasha-unisex\" width=\"620\" height=\"620\" \/><br \/>\n&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sasha Unisex es una tatuadora profesional de origen ruso que imprime (o tat\u00faa, en este caso) un estilo muy personal en cada una de sus obras. El trabajo de Sasha se caracteriza por representar a todo tipo de animales creados a partir de formas poligonales, tatuados sobre la piel para despu\u00e9s ser coloreados con una&hellip; <a class=\"more-link\" href=\"https:\/\/ctrl-x.com.mx\/ctrlx\/los-coloridos-tatuajes-geometricos-de-sasha-unisex\/\">Seguir leyendo <span class=\"screen-reader-text\">Los coloridos tatuajes geom\u00e9tricos de Sasha Unisex<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":6068,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,18,53],"tags":[2085,2206,4100,4433,4474,4879,4885,4887],"class_list":["post-6054","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","category-diseno","category-tatuajes-2","tag-formas-poligonales","tag-geometricos","tag-profesional","tag-rusa","tag-sasha-unisex","tag-tatuadora","tag-tatuajes","tag-tatuajes-geometricos","entry"],"_links":{"self":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/6054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/comments?post=6054"}],"version-history":[{"count":0,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/6054\/revisions"}],"wp:attachment":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/media?parent=6054"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/categories?post=6054"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/tags?post=6054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}