{"id":10430,"date":"2015-06-16T09:21:48","date_gmt":"2015-06-16T14:21:48","guid":{"rendered":"http:\/\/ctrl-x.com.mx\/ctrlx\/?p=10430"},"modified":"2015-06-16T09:21:48","modified_gmt":"2015-06-16T14:21:48","slug":"aprende-chino-de-una-manera-facil-y-divertida","status":"publish","type":"post","link":"https:\/\/ctrl-x.com.mx\/ctrlx\/aprende-chino-de-una-manera-facil-y-divertida\/","title":{"rendered":"Aprende chino de una manera f\u00e1cil y divertida"},"content":{"rendered":"<h4>Aprender un idioma suele ser dif\u00edcil y complicado, y mas si es un idioma que no usa letras como el chino, a muchos les gastar\u00eda aprender este idioma pero por la complejidad quiz\u00e1 se desaniman.<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10432\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2015\/06\/Chineasy_FCPC_Small_700x394.png\" alt=\"Chineasy_FCPC_Small_700x394\" width=\"700\" height=\"394\" \/><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"  wp-image-10431 alignright\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2015\/06\/97-Chineasy_HIGHRES-IMG_0384.jpg\" alt=\"Shaolan Hsueh, Chineasy, Kickstarter@Robert Leslie 2013\" width=\"101\" height=\"151\" \/>La creadora de este sistema f\u00e1cil e intuitivo es <a href=\"http:\/\/chineasy.org\/about\/about-shaolan.aspx\" target=\"_blank\" rel=\"noopener noreferrer\">Shaolan<\/a>, se centra ahora en un proyecto social,<a href=\"http:\/\/chineasy.org\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Chineasy<\/a>. El objetivo final de Shaolan es reducir la gran muralla de la lengua china y permitir culturas oriental y occidental de comunicarse libremente.<br \/>\nEs evidente que la gente tiene hambre de aprender acerca de China. La gente est\u00e1 dispuesta a ser capaz de comunicarse con los 1,3 millones de personas. Sin embargo, no hay mucho por ah\u00ed para que puedan hacerlo. Mientras que toda la poblaci\u00f3n china est\u00e1 aprendiendo Ingl\u00e9s, es el momento para nosotros comprender realmente esta compleja econom\u00eda y la sociedad con nuestros propios ojos y el juicio. Conocer su lengua es el primer paso de beb\u00e9, pero crucial.<br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10433\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2015\/06\/pantallazo_q.png\" alt=\"pantallazo_q\" width=\"939\" height=\"368\" \/><br \/>\nLa agenda real detr\u00e1s de este proyecto es reducir la brecha entre el Este y el Oeste.<br \/>\n(Lecci\u00f3n de chino en 10 minutos &#8220;<em>activa los subtitlos<\/em>&#8220;)<br \/>\n<iframe loading=\"lazy\" title=\"Chineasy by ShaoLan: Learn Chinese DLD 2014\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/wQUEW04e_qo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\n&nbsp;<br \/>\n<iframe loading=\"lazy\" title=\"ShaoLan&#039;s Chineasy: Lesson 1\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/T5FNvW19GbA?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\n&nbsp;<\/p>\n<blockquote><p><strong><a href=\"http:\/\/chineasy.org\/\" target=\"_blank\" rel=\"noopener noreferrer\">chineasy.org<\/a><\/strong><\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Aprender un idioma suele ser dif\u00edcil y complicado, y mas si es un idioma que no usa letras como el chino, a muchos les gastar\u00eda aprender este idioma pero por la complejidad quiz\u00e1 se desaniman. La creadora de este sistema f\u00e1cil e intuitivo es Shaolan, se centra ahora en un proyecto social, Chineasy. El objetivo&hellip; <a class=\"more-link\" href=\"https:\/\/ctrl-x.com.mx\/ctrlx\/aprende-chino-de-una-manera-facil-y-divertida\/\">Seguir leyendo <span class=\"screen-reader-text\">Aprende chino de una manera f\u00e1cil y divertida<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10432,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,8,16,43],"tags":[988,989,2525,4135,4576],"class_list":["post-10430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-arte","category-blog","category-cultura","category-ocio","tag-chineasy","tag-chino","tag-idioma","tag-proyecto-social","tag-shaolan","entry"],"_links":{"self":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/10430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/comments?post=10430"}],"version-history":[{"count":0,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/10430\/revisions"}],"wp:attachment":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/media?parent=10430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/categories?post=10430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/tags?post=10430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}