{"id":10015,"date":"2015-05-11T09:04:52","date_gmt":"2015-05-11T14:04:52","guid":{"rendered":"http:\/\/ctrl-x.com.mx\/ctrlx\/?p=10015"},"modified":"2015-05-11T09:04:52","modified_gmt":"2015-05-11T14:04:52","slug":"este-14-de-mayo-a-android-vuelve-el-mitico-juego-snake","status":"publish","type":"post","link":"https:\/\/ctrl-x.com.mx\/ctrlx\/este-14-de-mayo-a-android-vuelve-el-mitico-juego-snake\/","title":{"rendered":"Este 14 de mayo vuelve a Android el m\u00edtico juego Snake"},"content":{"rendered":"<h4><strong>El Sr. Armanto, el creador del juego Snake, vuelve a revivir este juego\u00a0con el que muchos de nosotros hemos disfrutado de peque\u00f1os.<\/strong> Todo esto gracias a las ventas de los legendarios tel\u00e9fonos de Nokia que inclu\u00edan este juego por defecto.<\/h4>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-10016\" src=\"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-content\/uploads\/2015\/05\/ap_resize.png\" alt=\"ap_resize\" width=\"700\" height=\"382\" \/><br \/>\nEn mi caso, este juego lo disfrut\u00e9 muy poco porque r\u00e1pidamente apareci\u00f3 una tecnolog\u00eda m\u00e1s avanzada y pronto fue sustituido. Si no sab\u00e9is de qu\u00e9 trata este juego os lo explico, el funcionamiento es muy sencillo porque tienes que <strong>controlar una serpiente que crece poco a poco cada vez que engulle una flor<\/strong> y evitar chocar con tu propio cuerpo y las paredes para que no se manifieste un \u201cGame Over\u201d.<br \/>\n<strong>El creador del juego junto con Rumilus Design ha creado una versi\u00f3n basada en el m\u00edtico Snake pero con unos gr\u00e1ficos m\u00e1s actualizados.<\/strong> Adem\u00e1s, incluyen nuevas funciones que entre ellas destaca, el <strong>poder retroceder en el tiempo despu\u00e9s de chocar.<\/strong> De la misma manera, para seguir avanzando incorporan con una \u201ctienda de frutas\u201d donde conseguiremos m\u00e1s niveles y objetos nuevos que se consiguen pagando con las frutas recogidas o a trav\u00e9s de dinero real, lo que viene a ser compras In-App. A continuaci\u00f3n os dejo el v\u00eddeo demostrativo:<br \/>\n<iframe loading=\"lazy\" title=\"Snake Rewind - May 14th\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/5i-Lvla_wt8?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><br \/>\nEl juego va a gustar porque los jugadores de este juego en el pasado ahora lo pueden revivir en esta versi\u00f3n sus viciadas al Snake.<br \/>\n&nbsp;<br \/>\nFuente:proandroid.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Sr. Armanto, el creador del juego Snake, vuelve a revivir este juego\u00a0con el que muchos de nosotros hemos disfrutado de peque\u00f1os. Todo esto gracias a las ventas de los legendarios tel\u00e9fonos de Nokia que inclu\u00edan este juego por defecto. En mi caso, este juego lo disfrut\u00e9 muy poco porque r\u00e1pidamente apareci\u00f3 una tecnolog\u00eda m\u00e1s&hellip; <a class=\"more-link\" href=\"https:\/\/ctrl-x.com.mx\/ctrlx\/este-14-de-mayo-a-android-vuelve-el-mitico-juego-snake\/\">Seguir leyendo <span class=\"screen-reader-text\">Este 14 de mayo vuelve a Android el m\u00edtico juego Snake<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":10016,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,8,23,31],"tags":[334,1295,2167,2786,3303,4430,4554,4678,4744],"class_list":["post-10015","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-app","category-blog","category-geek","category-juegos","tag-android","tag-crece","tag-game-over","tag-juego","tag-mitico","tag-rumilus-design","tag-serpiente","tag-snake","tag-sr-armanto","entry"],"_links":{"self":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/10015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/comments?post=10015"}],"version-history":[{"count":0,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/posts\/10015\/revisions"}],"wp:attachment":[{"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/media?parent=10015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/categories?post=10015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ctrl-x.com.mx\/ctrlx\/wp-json\/wp\/v2\/tags?post=10015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}